{"id":744,"count":47,"description":"Le borse a tracolla Cnoles sono pensate per le donne che affrontano la giornata senza mai rallentare. Realizzate in vera pelle, ogni modello unisce una silhouette compatta a una tracolla regolabile, dalle eleganti borse a tracolla con catena alle strutturate forme a secchiello \u2014 compagne perfette per l'ufficio, i viaggi e le commissioni quotidiane.Oltre alla funzionalit\u00e0, le nostre borse a tracolla portano un tocco di raffinatezza: forme a spalla ispirate al vintage, cornici scolpite a semicerchio e piccole pochette da sera pronte per le occasioni serali. Ogni pezzo \u00e8 costruito per mantenere la forma e ammorbidirsi con il tempo. Esplora la collezione e trova la borsa a tracolla perfetta per la tua giornata.","link":"https:\/\/cnolesbag.store\/it\/product-category\/borsa-a-tracolla\/","name":"Borsa a tracolla","slug":"borsa-a-tracolla","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/cnolesbag.store\/it\/wp-json\/wp\/v2\/product_cat\/744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnolesbag.store\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cnolesbag.store\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/cnolesbag.store\/it\/wp-json\/wp\/v2\/product?product_cat=744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}