{"id":733,"count":33,"description":"Entdecken Sie Cnoles Schultertaschen aus Leder, gefertigt aus echtem Leder f\u00fcr einen Look, der m\u00fchelos vom Tag in den Abend \u00fcbergeht. Von strukturierten Modellen mit Henkel bis zu weichen Bucket- und Umh\u00e4ngeformen verbindet jedes St\u00fcck klare Linien mit allt\u00e4glicher Praktikabilit\u00e4t.Ob als eleganter Begleiter f\u00fcrs B\u00fcro, leichte Option f\u00fcr die Reise oder stilvoller Abschluss f\u00fcr einen Abend \u2013 unsere Schultertaschen-Kollektion bietet vielseitige Designs in zeitlosen Farben. Entdecken Sie die Kollektion und finden Sie die Leder-Schultertasche, die zu Ihrer Alltagsgeschichte passt.","link":"https:\/\/cnolesbag.store\/de\/product-category\/schultertasche\/","name":"Schultertasche","slug":"schultertasche","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/cnolesbag.store\/de\/wp-json\/wp\/v2\/product_cat\/733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnolesbag.store\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/cnolesbag.store\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/cnolesbag.store\/de\/wp-json\/wp\/v2\/product?product_cat=733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}